{"id":670,"date":"2014-12-27T17:08:52","date_gmt":"2014-12-27T16:08:52","guid":{"rendered":"http:\/\/www.walnutlodge.nl\/?page_id=670"},"modified":"2025-07-31T09:51:19","modified_gmt":"2025-07-31T08:51:19","slug":"chi-siamo","status":"publish","type":"page","link":"https:\/\/www.walnutlodge.nl\/it\/chi-siamo\/","title":{"rendered":"Chi siamo"},"content":{"rendered":"<p style=\"text-align: justify;\">Walnut Lodge \u00e8 stato costruito nel 1906 ed \u00e8 stato ampiamente rinnovato nel corso degli anni. Dal 1960 fino al 2002 ha operato come Hotel &#8220;Bergzicht&#8221; (Vista di Montagna).<br \/>\nDopo una completa ristrutturazione nel 2014, \u00e8 stato aperto come un Bed &amp; Breakfast sotto il nuovo nome di &#8220;Walnut Lodge&#8221;, riferendosi al grande albero di noce nel giardino posteriore, che fornisce anche una casa a scoiattoli rossi.<\/p>\n<p>Il Lodge \u00e8 la casa di Gertjan Meulenbeld e Brian Elliott. Gertjan \u00e8 cresciuto a Maastricht, nei Paesi Bassi. Dopo gli studi di Amsterdam, ha vissuto in Italia per 3 anni e successivamente, nel 1987, \u00e8 emigrato in Australia, dove \u00e8 rimasto\u00a0 per 27 anni. Brian \u00e8 nato in Australia da genitori irlandese\/scozzesi e, dopo 15 mesi vissuti a Edimburgo, a met\u00e0 degli anni &#8217;90, \u00e8 tornato in Australia.<\/p>\n<p><a href=\"https:\/\/www.walnutlodge.nl\/wp-content\/uploads\/2025\/07\/About-us-photo.jpeg\" rel=\"lightbox[670]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2245\" src=\"https:\/\/www.walnutlodge.nl\/wp-content\/uploads\/2025\/07\/About-us-photo.jpeg\" alt=\"\" width=\"640\" height=\"420\" \/><\/a><br \/>\nOra sono emigrati in Olanda per seguire il loro sogno di vivere in Europa e condividere la loro casa in modo che altri possano godere della rinomata ospitalit\u00e0 del Limburgo meridionale.<\/p>\n<p>Pumpkin \u00e8 il loro gatto color zenzero, anche lui emigrato dall&#8217;Australia a Noorbeek. Sentitevi liberi di viziarlo se lo vedete in giro.<\/p>\n<h1 class=\"entry-title\">Links<\/h1>\n<div id=\"TA_cdsratingsonlynarrow687\" class=\"TA_cdsratingsonlynarrow\">\n<ul id=\"YJ7ugt0zSixe\" class=\"TA_links ZpzUxI5gc\">\n<li id=\"a9kkSdtxZa4\" class=\"N7J4ZxC5K\"><a href=\"https:\/\/www.tripadvisor.it\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" src=\"https:\/\/www.tripadvisor.it\/img\/cdsi\/img2\/branding\/tripadvisor_logo_transp_340x80-18034-2.png\" alt=\"TripAdvisor\" \/><\/a><\/li>\n<\/ul>\n<\/div>\n<p><script async=\"\" src=\"https:\/\/www.jscache.com\/wejs?wtype=cdsratingsonlynarrow&amp;uniq=687&amp;locationId=7728543&amp;lang=it&amp;border=true&amp;display_version=2\" data-loadtrk=\"\" onload=\"this.loadtrk=true\"><\/script><\/p>\n<table id=\"linkstable\" style=\"height: 252px;\" width=\"586\">\n<tbody>\n<tr>\n<td><a href=\"http:\/\/www.holland-vakantiehuis.nl\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.holland-vakantiehuis.nl\/headers\/banner_holland_300_60.jpg\" alt=\"www.holland-vakantiehuis.nl\" width=\"300\" height=\"60\" border=\"0\" \/><\/a><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><a href=\"http:\/\/www.purpleroofs.com\/europe\/netherlands.html\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.purpleroofs.com\/images\/purple-roofs-logo-new.jpg\" alt=\"http:\/\/www.purpleroofs.com\/europe\/netherlands.html\" width=\"300\" height=\"90\" border=\"0\" \/><\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Walnut Lodge \u00e8 stato costruito nel 1906 ed \u00e8 stato ampiamente rinnovato nel corso degli anni. Dal 1960 fino al 2002 ha operato come Hotel &#8220;Bergzicht&#8221; (Vista di Montagna). Dopo una completa ristrutturazione nel 2014, \u00e8 stato aperto come un Bed &amp; Breakfast sotto il nuovo nome di &#8220;Walnut Lodge&#8221;, riferendosi al grande albero di&nbsp;<a href=\"https:\/\/www.walnutlodge.nl\/it\/chi-siamo\/\"><i class=\"fa fa-long-arrow-right\"><\/i><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"class_list":["post-670","page","type-page","status-publish","hentry","entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.walnutlodge.nl\/it\/wp-json\/wp\/v2\/pages\/670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.walnutlodge.nl\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.walnutlodge.nl\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.walnutlodge.nl\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.walnutlodge.nl\/it\/wp-json\/wp\/v2\/comments?post=670"}],"version-history":[{"count":8,"href":"https:\/\/www.walnutlodge.nl\/it\/wp-json\/wp\/v2\/pages\/670\/revisions"}],"predecessor-version":[{"id":2258,"href":"https:\/\/www.walnutlodge.nl\/it\/wp-json\/wp\/v2\/pages\/670\/revisions\/2258"}],"wp:attachment":[{"href":"https:\/\/www.walnutlodge.nl\/it\/wp-json\/wp\/v2\/media?parent=670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}